{"id":691,"date":"2017-03-27T11:54:25","date_gmt":"2017-03-27T09:54:25","guid":{"rendered":"http:\/\/blog.ostwestfalen.ihk.de\/innovation\/?p=691"},"modified":"2017-03-27T11:54:25","modified_gmt":"2017-03-27T09:54:25","slug":"zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen","status":"publish","type":"post","link":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/","title":{"rendered":"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen"},"content":{"rendered":"<p>BMWI erteilt Konsortium unter F\u00fchrung der Universit\u00e4t Siegen mit Partnern aus Bochum, Brandenburg und Sachsen den Zuschlag. Wirtschaftsminister Garrelt Duin: \u201eMit Siegen wird es neben dem Kompetenzzentrum Dortmund-Aachen-Ostwestfalen eine weitere wichtige Informationsplattform f\u00fcr Klein- und Mittelbetriebe in Nordrhein-Westfalen geben. Der Zuschlag untermauert die Leistungskraft der starken Forschungs- und Mittelstandsregion S\u00fcdwestfalen. Dieses zweite Zentrum in Nordrhein-Westfalen ist ein weiterer wichtiger Baustein unserer Informationsinfrastruktur f\u00fcr die mittelst\u00e4ndische Wirtschaft. Dies ist ein richtig guter Tag f\u00fcr die Digitalstandorte S\u00fcdwestfalen, Bochum und Nordrhein-Westfalen insgesamt.\u201c<br \/>\n<a href=\"http:\/\/www.mittelstand-digital.de\/DE\/Foerderinitiativen\/Mittelstand-4-0\/kompetenzzentren.html\" target=\"_blank\">http:\/\/www.mittelstand-digital.de\/DE\/Foerderinitiativen\/Mittelstand-4-0\/kompetenzzentren.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BMWI erteilt Konsortium unter F\u00fchrung der Universit\u00e4t Siegen mit Partnern aus Bochum, Brandenburg und Sachsen den Zuschlag. Wirtschaftsminister Garrelt Duin: \u201eMit Siegen wird es neben dem Kompetenzzentrum Dortmund-Aachen-Ostwestfalen eine weitere wichtige Informationsplattform f\u00fcr Klein- und Mittelbetriebe in Nordrhein-Westfalen geben. Der Zuschlag untermauert die Leistungskraft der starken Forschungs- und Mittelstandsregion S\u00fcdwestfalen. Dieses zweite Zentrum in Nordrhein-Westfalen [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93,72],"tags":[],"class_list":["post-691","post","type-post","status-publish","format-standard","hentry","category-digitalisierung","category-foerderprogramme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen - KnowHow Ostwestfalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen - KnowHow Ostwestfalen\" \/>\n<meta property=\"og:description\" content=\"BMWI erteilt Konsortium unter F\u00fchrung der Universit\u00e4t Siegen mit Partnern aus Bochum, Brandenburg und Sachsen den Zuschlag. Wirtschaftsminister Garrelt Duin: \u201eMit Siegen wird es neben dem Kompetenzzentrum Dortmund-Aachen-Ostwestfalen eine weitere wichtige Informationsplattform f\u00fcr Klein- und Mittelbetriebe in Nordrhein-Westfalen geben. Der Zuschlag untermauert die Leistungskraft der starken Forschungs- und Mittelstandsregion S\u00fcdwestfalen. Dieses zweite Zentrum in Nordrhein-Westfalen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow Ostwestfalen\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-27T09:54:25+00:00\" \/>\n<meta name=\"author\" content=\"vvalter\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vvalter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/\"},\"author\":{\"name\":\"vvalter\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"headline\":\"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen\",\"datePublished\":\"2017-03-27T09:54:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/\"},\"wordCount\":104,\"commentCount\":0,\"articleSection\":[\"Digitalisierung\",\"F\u00f6rderprogramme\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/\",\"name\":\"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen - KnowHow Ostwestfalen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\"},\"datePublished\":\"2017-03-27T09:54:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/27\\\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\",\"name\":\"KnowHow Ostwestfalen\",\"description\":\"Innovation &amp; Technologietransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\",\"name\":\"vvalter\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen - KnowHow Ostwestfalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/","og_locale":"de_DE","og_type":"article","og_title":"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen - KnowHow Ostwestfalen","og_description":"BMWI erteilt Konsortium unter F\u00fchrung der Universit\u00e4t Siegen mit Partnern aus Bochum, Brandenburg und Sachsen den Zuschlag. Wirtschaftsminister Garrelt Duin: \u201eMit Siegen wird es neben dem Kompetenzzentrum Dortmund-Aachen-Ostwestfalen eine weitere wichtige Informationsplattform f\u00fcr Klein- und Mittelbetriebe in Nordrhein-Westfalen geben. Der Zuschlag untermauert die Leistungskraft der starken Forschungs- und Mittelstandsregion S\u00fcdwestfalen. Dieses zweite Zentrum in Nordrhein-Westfalen [&hellip;]","og_url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/","og_site_name":"KnowHow Ostwestfalen","article_published_time":"2017-03-27T09:54:25+00:00","author":"vvalter","twitter_misc":{"Verfasst von":"vvalter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/#article","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/"},"author":{"name":"vvalter","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"headline":"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen","datePublished":"2017-03-27T09:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/"},"wordCount":104,"commentCount":0,"articleSection":["Digitalisierung","F\u00f6rderprogramme"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/","name":"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen - KnowHow Ostwestfalen","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website"},"datePublished":"2017-03-27T09:54:25+00:00","author":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"breadcrumb":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/27\/zweites-kompetenzzentrum-mittelstand-4-0-kommt-nach-siegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/"},{"@type":"ListItem","position":2,"name":"Zweites Kompetenzzentrum Mittelstand 4.0 kommt nach Siegen"}]},{"@type":"WebSite","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/","name":"KnowHow Ostwestfalen","description":"Innovation &amp; Technologietransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77","name":"vvalter"}]}},"_links":{"self":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/comments?post=691"}],"version-history":[{"count":1,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/691\/revisions"}],"predecessor-version":[{"id":692,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/691\/revisions\/692"}],"wp:attachment":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/media?parent=691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/categories?post=691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/tags?post=691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}