{"id":686,"date":"2017-03-23T14:27:55","date_gmt":"2017-03-23T13:27:55","guid":{"rendered":"http:\/\/blog.ostwestfalen.ihk.de\/innovation\/?p=686"},"modified":"2017-03-23T14:27:55","modified_gmt":"2017-03-23T13:27:55","slug":"vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung","status":"publish","type":"post","link":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/","title":{"rendered":"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c"},"content":{"rendered":"<p>14 regionale Partner haben in den vergangenen drei Jahren an der Entwicklung einer mitdenkenden Wohnung gearbeitet und geforscht. Ein intelligenter Eingangsbereich, ein pers\u00f6nlicher Trainer, eine assistierende K\u00fcche und ein virtueller Dialogassistent k\u00f6nnen ihre jeweiligen Nutzer und Nutzerinnen wahrnehmen und erkennen, passgenaue Funktionen anbieten und individuelle Unterst\u00fctzung und Assistenz im Alltag bieten. In Hinblick auf den Projektabschluss werden die Ergebnisse von Wirtschaft und Wissenschaft pr\u00e4sentiert. Es erwartet Sie unter anderem: eine Podiumsdiskussion der Projektpartner, die Vorstellung der KogniHome-Demonstratoren sowie die Ergebnisse im Projekt- und Filmvortrag. Info und Anmeldung:<br \/>\n<a href=\"https:\/\/www.kogni-home.de\/abschlussveranstaltung\" target=\"_blank\">https:\/\/www.kogni-home.de\/abschlussveranstaltung<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>14 regionale Partner haben in den vergangenen drei Jahren an der Entwicklung einer mitdenkenden Wohnung gearbeitet und geforscht. Ein intelligenter Eingangsbereich, ein pers\u00f6nlicher Trainer, eine assistierende K\u00fcche und ein virtueller Dialogassistent k\u00f6nnen ihre jeweiligen Nutzer und Nutzerinnen wahrnehmen und erkennen, passgenaue Funktionen anbieten und individuelle Unterst\u00fctzung und Assistenz im Alltag bieten. In Hinblick auf den [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,10],"tags":[],"class_list":["post-686","post","type-post","status-publish","format-standard","hentry","category-foerderprogramme","category-veranstaltungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c - KnowHow Ostwestfalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c - KnowHow Ostwestfalen\" \/>\n<meta property=\"og:description\" content=\"14 regionale Partner haben in den vergangenen drei Jahren an der Entwicklung einer mitdenkenden Wohnung gearbeitet und geforscht. Ein intelligenter Eingangsbereich, ein pers\u00f6nlicher Trainer, eine assistierende K\u00fcche und ein virtueller Dialogassistent k\u00f6nnen ihre jeweiligen Nutzer und Nutzerinnen wahrnehmen und erkennen, passgenaue Funktionen anbieten und individuelle Unterst\u00fctzung und Assistenz im Alltag bieten. In Hinblick auf den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow Ostwestfalen\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-23T13:27:55+00:00\" \/>\n<meta name=\"author\" content=\"vvalter\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vvalter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/\"},\"author\":{\"name\":\"vvalter\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"headline\":\"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c\",\"datePublished\":\"2017-03-23T13:27:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/\"},\"wordCount\":109,\"commentCount\":0,\"articleSection\":[\"F\u00f6rderprogramme\",\"Veranstaltungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/\",\"name\":\"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c - KnowHow Ostwestfalen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\"},\"datePublished\":\"2017-03-23T13:27:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2017\\\/03\\\/23\\\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\",\"name\":\"KnowHow Ostwestfalen\",\"description\":\"Innovation &amp; Technologietransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\",\"name\":\"vvalter\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c - KnowHow Ostwestfalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/","og_locale":"de_DE","og_type":"article","og_title":"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c - KnowHow Ostwestfalen","og_description":"14 regionale Partner haben in den vergangenen drei Jahren an der Entwicklung einer mitdenkenden Wohnung gearbeitet und geforscht. Ein intelligenter Eingangsbereich, ein pers\u00f6nlicher Trainer, eine assistierende K\u00fcche und ein virtueller Dialogassistent k\u00f6nnen ihre jeweiligen Nutzer und Nutzerinnen wahrnehmen und erkennen, passgenaue Funktionen anbieten und individuelle Unterst\u00fctzung und Assistenz im Alltag bieten. In Hinblick auf den [&hellip;]","og_url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/","og_site_name":"KnowHow Ostwestfalen","article_published_time":"2017-03-23T13:27:55+00:00","author":"vvalter","twitter_misc":{"Verfasst von":"vvalter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/#article","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/"},"author":{"name":"vvalter","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"headline":"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c","datePublished":"2017-03-23T13:27:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/"},"wordCount":109,"commentCount":0,"articleSection":["F\u00f6rderprogramme","Veranstaltungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/","name":"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c - KnowHow Ostwestfalen","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website"},"datePublished":"2017-03-23T13:27:55+00:00","author":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"breadcrumb":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2017\/03\/23\/vormerken-23-juni-2017-bielefeld-abschlussveranstaltung-zum-bmbf-gefoerderten-innovationscluster-kognihome-die-mitdenkende-wohnung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/"},{"@type":"ListItem","position":2,"name":"Vormerken: 23. Juni 2017, Bielefeld: Abschlussveranstaltung zum BMBF gef\u00f6rderten Innovationscluster \u201eKogniHome \u2013 die mitdenkende Wohnung\u201c"}]},{"@type":"WebSite","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/","name":"KnowHow Ostwestfalen","description":"Innovation &amp; Technologietransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77","name":"vvalter"}]}},"_links":{"self":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":1,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"predecessor-version":[{"id":687,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/686\/revisions\/687"}],"wp:attachment":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/tags?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}