{"id":499,"date":"2016-11-03T08:35:47","date_gmt":"2016-11-03T07:35:47","guid":{"rendered":"http:\/\/blog.ostwestfalen.ihk.de\/innovation\/?p=499"},"modified":"2016-11-03T08:35:47","modified_gmt":"2016-11-03T07:35:47","slug":"buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu","status":"publish","type":"post","link":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/","title":{"rendered":"B\u00fcndnis &#8222;Zukunft der Industrie&#8220; fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU"},"content":{"rendered":"<p>Der deutsche Mittelstand muss in seinen Forschungs- und Innovationsaktivit\u00e4ten auch steuerlich unterst\u00fctzt werden: Daf\u00fcr hat sich Mitte September 2016 das B\u00fcndnis &#8222;Zukunft der Industrie&#8220; ausgesprochen, dem auch der Deutsche Industrie- und Handelskammertag (DIHK) angeh\u00f6rt.<br \/>\nIn einer gemeinsamen Erkl\u00e4rung \u00e4u\u00dfern sich die insgesamt 17 Partner aus Industrie, Gewerkschaften, Arbeitgebern und Politik besorgt dar\u00fcber, dass der Anteil der Innovationsausgaben kleiner und mittlerer Unternehmen (KMU) bis 500 Besch\u00e4ftigte an den gesamten Innovationsausgaben seit Jahren sinkt.<br \/>\nSie finden die komplette Erkl\u00e4rung auf der Website des B\u00fcndnisses &#8222;Zukunft der Industrie&#8220;:<br \/>\n<a href=\"https:\/\/www.buendnis-fuer-industrie.de\/das-buendnis\/aktuelles\/buendnis-zukunft-der-industrie-steuerliche-fe-foerderung-von-kleinen-und-mittleren-unternehmen-bis-500-beschaeftigte-als-ersten-schritt-jetzt-endlich-umsetzen\/\" target=\"_blank\">https:\/\/www.buendnis-fuer-industrie.de\/das-buendnis\/aktuelles\/buendnis-zukunft-der-industrie-steuerliche-fe-foerderung-von-kleinen-und-mittleren-unternehmen-bis-500-beschaeftigte-als-ersten-schritt-jetzt-endlich-umsetzen\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der deutsche Mittelstand muss in seinen Forschungs- und Innovationsaktivit\u00e4ten auch steuerlich unterst\u00fctzt werden: Daf\u00fcr hat sich Mitte September 2016 das B\u00fcndnis &#8222;Zukunft der Industrie&#8220; ausgesprochen, dem auch der Deutsche Industrie- und Handelskammertag (DIHK) angeh\u00f6rt. In einer gemeinsamen Erkl\u00e4rung \u00e4u\u00dfern sich die insgesamt 17 Partner aus Industrie, Gewerkschaften, Arbeitgebern und Politik besorgt dar\u00fcber, dass der Anteil [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,84],"tags":[],"class_list":["post-499","post","type-post","status-publish","format-standard","hentry","category-foerderprogramme","category-industrie-4-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B\u00fcndnis &quot;Zukunft der Industrie&quot; fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU - KnowHow Ostwestfalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00fcndnis &quot;Zukunft der Industrie&quot; fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU - KnowHow Ostwestfalen\" \/>\n<meta property=\"og:description\" content=\"Der deutsche Mittelstand muss in seinen Forschungs- und Innovationsaktivit\u00e4ten auch steuerlich unterst\u00fctzt werden: Daf\u00fcr hat sich Mitte September 2016 das B\u00fcndnis &#8222;Zukunft der Industrie&#8220; ausgesprochen, dem auch der Deutsche Industrie- und Handelskammertag (DIHK) angeh\u00f6rt. In einer gemeinsamen Erkl\u00e4rung \u00e4u\u00dfern sich die insgesamt 17 Partner aus Industrie, Gewerkschaften, Arbeitgebern und Politik besorgt dar\u00fcber, dass der Anteil [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow Ostwestfalen\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-03T07:35:47+00:00\" \/>\n<meta name=\"author\" content=\"vvalter\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vvalter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/\"},\"author\":{\"name\":\"vvalter\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"headline\":\"B\u00fcndnis &#8222;Zukunft der Industrie&#8220; fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU\",\"datePublished\":\"2016-11-03T07:35:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/\"},\"wordCount\":114,\"commentCount\":0,\"articleSection\":[\"F\u00f6rderprogramme\",\"Industrie 4.0\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/\",\"name\":\"B\u00fcndnis \\\"Zukunft der Industrie\\\" fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU - KnowHow Ostwestfalen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\"},\"datePublished\":\"2016-11-03T07:35:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/11\\\/03\\\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00fcndnis &#8222;Zukunft der Industrie&#8220; fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\",\"name\":\"KnowHow Ostwestfalen\",\"description\":\"Innovation &amp; Technologietransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\",\"name\":\"vvalter\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00fcndnis \"Zukunft der Industrie\" fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU - KnowHow Ostwestfalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/","og_locale":"de_DE","og_type":"article","og_title":"B\u00fcndnis \"Zukunft der Industrie\" fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU - KnowHow Ostwestfalen","og_description":"Der deutsche Mittelstand muss in seinen Forschungs- und Innovationsaktivit\u00e4ten auch steuerlich unterst\u00fctzt werden: Daf\u00fcr hat sich Mitte September 2016 das B\u00fcndnis &#8222;Zukunft der Industrie&#8220; ausgesprochen, dem auch der Deutsche Industrie- und Handelskammertag (DIHK) angeh\u00f6rt. In einer gemeinsamen Erkl\u00e4rung \u00e4u\u00dfern sich die insgesamt 17 Partner aus Industrie, Gewerkschaften, Arbeitgebern und Politik besorgt dar\u00fcber, dass der Anteil [&hellip;]","og_url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/","og_site_name":"KnowHow Ostwestfalen","article_published_time":"2016-11-03T07:35:47+00:00","author":"vvalter","twitter_misc":{"Verfasst von":"vvalter","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/#article","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/"},"author":{"name":"vvalter","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"headline":"B\u00fcndnis &#8222;Zukunft der Industrie&#8220; fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU","datePublished":"2016-11-03T07:35:47+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/"},"wordCount":114,"commentCount":0,"articleSection":["F\u00f6rderprogramme","Industrie 4.0"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/","name":"B\u00fcndnis \"Zukunft der Industrie\" fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU - KnowHow Ostwestfalen","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website"},"datePublished":"2016-11-03T07:35:47+00:00","author":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"breadcrumb":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/11\/03\/buendnis-zukunft-der-industrie-fordert-steuerliche-fe-hilfen-fuer-kmu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/"},{"@type":"ListItem","position":2,"name":"B\u00fcndnis &#8222;Zukunft der Industrie&#8220; fordert steuerliche F&amp;E-Hilfen f\u00fcr KMU"}]},{"@type":"WebSite","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/","name":"KnowHow Ostwestfalen","description":"Innovation &amp; Technologietransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77","name":"vvalter"}]}},"_links":{"self":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/comments?post=499"}],"version-history":[{"count":1,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/499\/revisions"}],"predecessor-version":[{"id":500,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/499\/revisions\/500"}],"wp:attachment":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/media?parent=499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/categories?post=499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/tags?post=499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}