{"id":168,"date":"2016-03-08T10:34:18","date_gmt":"2016-03-08T09:34:18","guid":{"rendered":"http:\/\/blog.ostwestfalen.ihk.de\/innovation\/?p=168"},"modified":"2016-03-08T10:34:18","modified_gmt":"2016-03-08T09:34:18","slug":"zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht","status":"publish","type":"post","link":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/","title":{"rendered":"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht"},"content":{"rendered":"<p><strong>Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; unter Schirmherrschaft von Wirtschaftsminister Garrelt Duin geht in die zweite Runde \/ Bewerbungen bis 10. April 2016 unter <a href=\"http:\/\/www.nrw-wirtschaft-im-wandel.de\" target=\"_blank\">www.nrw-wirtschaft-im-wandel.de<\/a> m\u00f6glich<\/strong><\/p>\n<p>Berlin\/D\u00fcsseldorf, 7. M\u00e4rz 2016 \u2013 Ab sofort k\u00f6nnen sich innovative Unternehmen aus Nordrhein-Westfalen wieder im Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; bewerben. Gesucht werden engagierte und kreative Impulsgeber, die den industriellen Transformationsprozess des Bundeslandes vorantreiben. Ob traditionsreicher Gro\u00dfkonzern oder aufstrebender Mittelst\u00e4ndler: Mit dem Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220;, der bereits zum zweiten Mal unter der Schirmherrschaft von Wirtschaftsminister Garrelt Duin steht, wollen die Initiative \u201eDeutschland \u2013 Land der Ideen&#8220;, die Rheinische Post und die Deutsche Bank den Vorreitern des Wandels eine \u00f6ffentliche B\u00fchne bereiten und die Innovationskraft des Standortes sichtbar machen. Als neuer Partner wird die Wirtschaftspr\u00fcfungsgesellschaft PricewaterhouseCoopers (PwC) den Wettbewerb unterst\u00fctzen.<\/p>\n<p>Engagierte Unternehmen, die den Transformationsprozess bereits erfolgreich gemeistert haben, k\u00f6nnen sich bis zum 10. April 2016 unter www.nrw-wirtschaft-im-wandel.de bewerben. Die Preistr\u00e4ger erhalten im Rahmen einer feierlichen Preisverleihung eine Auszeichnung von NRW-Wirtschaftsminister Garrelt Duin. In einer gro\u00dfen Portr\u00e4tserie in der Rheinischen Post wird ihr vorbildliches Vorangehen dar\u00fcber hinaus der \u00d6ffentlichkeit vorgestellt.<\/p>\n<p>\u201eDie Preistr\u00e4ger des vergangenen Jahres haben gezeigt, dass wir in Nordrhein-Westfalen zahlreiche Unternehmen vorfinden, die als Aush\u00e4ngeschilder ihrer Region wegweisende Impulse, nicht nur f\u00fcr die Zukunft des Standortes, sondern auch f\u00fcr ganz Deutschland liefern&#8220;, so Holger L\u00f6sch, Mitglied der Hauptgesch\u00e4ftsf\u00fchrung, Bundesverband der Deutschen Industrie e.V. und Vorsitzender des Aufsichtsrats der Land der Ideen Management GmbH.<\/p>\n<p>\u201eNordrhein-Westfalen vollzieht wie kaum ein anderes Bundesland einen tiefgreifenden Strukturwandel. Wie innovativ und kreativ sich viele Unternehmen \u2013 vom Gro\u00dfkonzern bis zum kleinen Handwerksbetrieb \u2013 den Herausforderungen wie etwa der Globalisierung und Digitalisierung stellen, konnten wir bei der ersten Auflage des Wettbewerbs sehen. Mit der Neuauflage m\u00f6chten wir daher erneut erfolgreichen Pionieren des Wandels eine B\u00fchne bieten&#8220;, sagt Michael Br\u00f6cker, Chefredakteur der Rheinischen Post.<\/p>\n<p>Martin Renker, Sprecher der Gesch\u00e4ftsleitung Nordwest Deutsche Bank, unterstreicht: \u201eDie faszinierende St\u00e4rke der regionalen Wirtschaft erleben wir bei der Deutschen Bank Tag f\u00fcr Tag. Deshalb f\u00f6rdern wir den Wettbewerb; denn er bildet ein beispielhaftes Netzwerk von Unternehmern und Unternehmen, die verstanden haben, wie Zukunft geht.&#8220;<\/p>\n<p>Eine hochkar\u00e4tige Expertenjury aus Politik, Wirtschaft, Wissenschaft und Gesellschaft w\u00e4hlt unter allen Bewerbern die 20 Preistr\u00e4ger aus. Lernen Sie die Mitglieder der Jury kennen: <a href=\"https:\/\/www.land-der-ideen.de\/wettbewerbe-nrw-wirtschaft-im-wandel\" target=\"_blank\">https:\/\/www.land-der-ideen.de\/wettbewerbe-nrw-wirtschaft-im-wandel<\/a>.<\/p>\n<p><span style=\"text-decoration: underline\">\u00dcber den Wettbewerb<\/span><\/p>\n<p>Wo einst rauchende Schlote und graue Zechensiedlungen das Bild der wirtschaftlichen Kernregion Deutschlands dominierten, entwickelt sich seit Jahrzehnten ein moderner und vielf\u00e4ltig aufgestellter Wirtschaftsstandort. Dabei fordert und f\u00f6rdert der andauernde Strukturwandel von Unternehmen aller Branchen kreative Unternehmensstrategien, den Einsatz neuer Technologien und die dynamische Anpassung von Produktionsbedingungen. Diese Kreativit\u00e4t wird durch den Wettbewerb \u201eNRW \u2013 Wirtschaft im Wandel&#8220; transparent und soll zur Nachahmung anregen.<\/p>\n<p><span style=\"text-decoration: underline\">\u00dcber die Initiative \u201eDeutschland \u2013 Land der Ideen<\/span><\/p>\n<p>\u201eDeutschland \u2013 Land der Ideen&#8220; ist die gemeinsame Standortinitiative der Bundesregierung und der deutschen Wirtschaft, vertreten durch den Bundesverband der Deutschen Industrie (BDI). Gemeinsam engagieren sich Partner aus Politik, Wirtschaft, Kultur und Wissenschaft daf\u00fcr, weltweit f\u00fcr die Attraktivit\u00e4t des Standorts Deutschland zu werben und Innovationen aus Deutschland zu mehr Bekanntheit im In-und Ausland zu verhelfen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; unter Schirmherrschaft von Wirtschaftsminister Garrelt Duin geht in die zweite Runde \/ Bewerbungen bis 10. April 2016 unter www.nrw-wirtschaft-im-wandel.de m\u00f6glich Berlin\/D\u00fcsseldorf, 7. M\u00e4rz 2016 \u2013 Ab sofort k\u00f6nnen sich innovative Unternehmen aus Nordrhein-Westfalen wieder im Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; bewerben. Gesucht werden engagierte und kreative Impulsgeber, die den industriellen Transformationsprozess des [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,40],"tags":[54,55],"class_list":["post-168","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-ausschreibungen","tag-land-der-ideen","tag-wirtschaft-im-wandel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht - KnowHow Ostwestfalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht - KnowHow Ostwestfalen\" \/>\n<meta property=\"og:description\" content=\"Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; unter Schirmherrschaft von Wirtschaftsminister Garrelt Duin geht in die zweite Runde \/ Bewerbungen bis 10. April 2016 unter www.nrw-wirtschaft-im-wandel.de m\u00f6glich Berlin\/D\u00fcsseldorf, 7. M\u00e4rz 2016 \u2013 Ab sofort k\u00f6nnen sich innovative Unternehmen aus Nordrhein-Westfalen wieder im Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; bewerben. Gesucht werden engagierte und kreative Impulsgeber, die den industriellen Transformationsprozess des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow Ostwestfalen\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-08T09:34:18+00:00\" \/>\n<meta name=\"author\" content=\"vvalter\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vvalter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/\"},\"author\":{\"name\":\"vvalter\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"headline\":\"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht\",\"datePublished\":\"2016-03-08T09:34:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/\"},\"wordCount\":537,\"commentCount\":0,\"keywords\":[\"Land der Ideen\",\"Wirtschaft im Wandel\"],\"articleSection\":{\"1\":\"Ausschreibungen\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/\",\"name\":\"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht - KnowHow Ostwestfalen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\"},\"datePublished\":\"2016-03-08T09:34:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2016\\\/03\\\/08\\\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\",\"name\":\"KnowHow Ostwestfalen\",\"description\":\"Innovation &amp; Technologietransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\",\"name\":\"vvalter\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht - KnowHow Ostwestfalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/","og_locale":"de_DE","og_type":"article","og_title":"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht - KnowHow Ostwestfalen","og_description":"Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; unter Schirmherrschaft von Wirtschaftsminister Garrelt Duin geht in die zweite Runde \/ Bewerbungen bis 10. April 2016 unter www.nrw-wirtschaft-im-wandel.de m\u00f6glich Berlin\/D\u00fcsseldorf, 7. M\u00e4rz 2016 \u2013 Ab sofort k\u00f6nnen sich innovative Unternehmen aus Nordrhein-Westfalen wieder im Wettbewerb \u201eNRW-Wirtschaft im Wandel&#8220; bewerben. Gesucht werden engagierte und kreative Impulsgeber, die den industriellen Transformationsprozess des [&hellip;]","og_url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/","og_site_name":"KnowHow Ostwestfalen","article_published_time":"2016-03-08T09:34:18+00:00","author":"vvalter","twitter_misc":{"Verfasst von":"vvalter","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/#article","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/"},"author":{"name":"vvalter","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"headline":"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht","datePublished":"2016-03-08T09:34:18+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/"},"wordCount":537,"commentCount":0,"keywords":["Land der Ideen","Wirtschaft im Wandel"],"articleSection":{"1":"Ausschreibungen"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/","name":"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht - KnowHow Ostwestfalen","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website"},"datePublished":"2016-03-08T09:34:18+00:00","author":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"breadcrumb":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2016\/03\/08\/zukunftsstarke-unternehmen-aus-nordrhein-westfalen-fuer-die-industrie-von-morgen-gesucht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/"},{"@type":"ListItem","position":2,"name":"Zukunftsstarke Unternehmen aus Nordrhein-Westfalen f\u00fcr die Industrie von morgen gesucht"}]},{"@type":"WebSite","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/","name":"KnowHow Ostwestfalen","description":"Innovation &amp; Technologietransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77","name":"vvalter"}]}},"_links":{"self":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/comments?post=168"}],"version-history":[{"count":1,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/168\/revisions"}],"predecessor-version":[{"id":169,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/168\/revisions\/169"}],"wp:attachment":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/media?parent=168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/categories?post=168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/tags?post=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}