{"id":1190,"date":"2018-06-13T14:35:51","date_gmt":"2018-06-13T12:35:51","guid":{"rendered":"http:\/\/blog.ostwestfalen.ihk.de\/innovation\/?p=1190"},"modified":"2018-06-13T14:35:51","modified_gmt":"2018-06-13T12:35:51","slug":"frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz","status":"publish","type":"post","link":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/","title":{"rendered":"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz"},"content":{"rendered":"<p>Staatspr\u00e4sident Emmanuel Macron hat am 29. M\u00e4rz 2018 im die Pl\u00e4ne der franz\u00f6sischen Regierung f\u00fcr das Themenfeld K\u00fcnstliche Intelligenz (KI) vorgestellt und damit den Anspruch Frankreichs untermauert, in diesem Bereich weltweit f\u00fchrend zu werden.<br \/>\nBis 2022 sollen insgesamt 1,5 Mrd. Euro f\u00fcr zahlreiche Ma\u00dfnahmen im Bereich KI bereitgestellt werden. Allein 800 Mio. Euro sollen in die f\u00fcr diesen Bereich zentrale Nanoelektronik-Forschung investiert werden. Bereits dieses Jahr sollen 100 Mio. Euro f\u00fcr KI-Start-ups aus dem Anfang des Jahres angek\u00fcndigten, zehn Mrd. Euro umfassenden Innovationsfonds bereitgestellt werden. Weitere 70 Mio. Euro sollen dann j\u00e4hrlich \u00fcber die \u00f6ffentliche Investitionsbank Bpifrance zur Verf\u00fcgung stehen. Neben dem Innovationsfonds und Bpifrance werden weitere, bereits existierende Fonds sowie umgewidmete Haushaltsmittel zur Finanzierung eingesetzt.<br \/>\nMobilit\u00e4t und Gesundheit sind die beiden priorit\u00e4ren Themenbereiche f\u00fcr die franz\u00f6sische Regierung. Bereits f\u00fcr April wird die franz\u00f6sische Strategie f\u00fcr autonomes Fahren erwartet und bis 2022 soll vollautomatisiertes Fahren (SAE-Level 4) in Frankreich zugelassen sein. Im Bereich Gesundheit soll ein \u201everitabler Gesundheitsdaten-Hub\u201c unter Leitung des Instituts f\u00fcr Gesundheitsdaten INDS (Institut Des Donn\u00e9es de Sant\u00e9) entstehen.<br \/>\n<em>Quelle: Kooperation International<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Staatspr\u00e4sident Emmanuel Macron hat am 29. M\u00e4rz 2018 im die Pl\u00e4ne der franz\u00f6sischen Regierung f\u00fcr das Themenfeld K\u00fcnstliche Intelligenz (KI) vorgestellt und damit den Anspruch Frankreichs untermauert, in diesem Bereich weltweit f\u00fchrend zu werden. Bis 2022 sollen insgesamt 1,5 Mrd. Euro f\u00fcr zahlreiche Ma\u00dfnahmen im Bereich KI bereitgestellt werden. Allein 800 Mio. Euro sollen in [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[141,143],"tags":[],"class_list":["post-1190","post","type-post","status-publish","format-standard","hentry","category-europa","category-kuenstliche-intelligenz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz - KnowHow Ostwestfalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz - KnowHow Ostwestfalen\" \/>\n<meta property=\"og:description\" content=\"Staatspr\u00e4sident Emmanuel Macron hat am 29. M\u00e4rz 2018 im die Pl\u00e4ne der franz\u00f6sischen Regierung f\u00fcr das Themenfeld K\u00fcnstliche Intelligenz (KI) vorgestellt und damit den Anspruch Frankreichs untermauert, in diesem Bereich weltweit f\u00fchrend zu werden. Bis 2022 sollen insgesamt 1,5 Mrd. Euro f\u00fcr zahlreiche Ma\u00dfnahmen im Bereich KI bereitgestellt werden. Allein 800 Mio. Euro sollen in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow Ostwestfalen\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-13T12:35:51+00:00\" \/>\n<meta name=\"author\" content=\"vvalter\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vvalter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/\"},\"author\":{\"name\":\"vvalter\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"headline\":\"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz\",\"datePublished\":\"2018-06-13T12:35:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/\"},\"wordCount\":197,\"articleSection\":[\"Europa\",\"K\u00fcnstliche Intelligenz\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/\",\"name\":\"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz - KnowHow Ostwestfalen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\"},\"datePublished\":\"2018-06-13T12:35:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/06\\\/13\\\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\",\"name\":\"KnowHow Ostwestfalen\",\"description\":\"Innovation &amp; Technologietransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\",\"name\":\"vvalter\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz - KnowHow Ostwestfalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/","og_locale":"de_DE","og_type":"article","og_title":"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz - KnowHow Ostwestfalen","og_description":"Staatspr\u00e4sident Emmanuel Macron hat am 29. M\u00e4rz 2018 im die Pl\u00e4ne der franz\u00f6sischen Regierung f\u00fcr das Themenfeld K\u00fcnstliche Intelligenz (KI) vorgestellt und damit den Anspruch Frankreichs untermauert, in diesem Bereich weltweit f\u00fchrend zu werden. Bis 2022 sollen insgesamt 1,5 Mrd. Euro f\u00fcr zahlreiche Ma\u00dfnahmen im Bereich KI bereitgestellt werden. Allein 800 Mio. Euro sollen in [&hellip;]","og_url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/","og_site_name":"KnowHow Ostwestfalen","article_published_time":"2018-06-13T12:35:51+00:00","author":"vvalter","twitter_misc":{"Verfasst von":"vvalter","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/#article","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/"},"author":{"name":"vvalter","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"headline":"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz","datePublished":"2018-06-13T12:35:51+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/"},"wordCount":197,"articleSection":["Europa","K\u00fcnstliche Intelligenz"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/","name":"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz - KnowHow Ostwestfalen","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website"},"datePublished":"2018-06-13T12:35:51+00:00","author":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"breadcrumb":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/06\/13\/frankreich-praesentiert-strategie-fuer-kuenstliche-intelligenz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/"},{"@type":"ListItem","position":2,"name":"Frankreich pr\u00e4sentiert Strategie f\u00fcr K\u00fcnstliche Intelligenz"}]},{"@type":"WebSite","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/","name":"KnowHow Ostwestfalen","description":"Innovation &amp; Technologietransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77","name":"vvalter"}]}},"_links":{"self":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":1,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"predecessor-version":[{"id":1191,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1190\/revisions\/1191"}],"wp:attachment":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}