{"id":1107,"date":"2018-04-06T09:55:36","date_gmt":"2018-04-06T07:55:36","guid":{"rendered":"http:\/\/blog.ostwestfalen.ihk.de\/innovation\/?p=1107"},"modified":"2018-04-06T09:55:36","modified_gmt":"2018-04-06T07:55:36","slug":"innovation-and-science-australia-veroeffentlicht-2030-plan","status":"publish","type":"post","link":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/","title":{"rendered":"Innovation and Science Australia ver\u00f6ffentlicht &#8222;2030 Plan&#8220;"},"content":{"rendered":"<p>Innovation and Science Australia (ISA) ist ein unabh\u00e4ngiges Gremium, das die australische Regierung zur strategischen Ausrichtung von Wissenschaft, Forschung und Innovation ber\u00e4t. Mit dem Ende Januar vorgestellten Plan Australia 2030: Prosperity through Innovation will ISA die Regierung dabei unterst\u00fctzen, die Innovationskraft des Landes zu st\u00e4rken und bis zum Jahr 2030 die vorhandenen Potentiale voll auszusch\u00f6pfen<br \/>\nDazu formuliert der Plan 30 Empfehlungen in den f\u00fcnf Feldern: Bildung, Industrie, Regierung, Forschung und Entwicklung sowie Kultur. Unter anderem fordert ISA, dass das australische Bildungssystem daf\u00fcr Sorge tragen m\u00fcsse, dass die f\u00fcr das Jahr 2030 relevanten Kompetenzen vermittelt werden, so dass der Wirtschaft ausreichend gut ausgebildete Fachkr\u00e4fte zur Verf\u00fcgung stehen. In diesem Zusammenhang fordert die ISA auch Reformen in der Zuwanderungspolitik. Zudem m\u00fcsse die Industrie mehr Anreize erhalten, in Forschung und Entwicklung zu investieren \u2013 insbesondere in den Bereichen K\u00fcnstliche Intelligenz und Maschinelles Lernen \u2013 und junge Unternehmen st\u00e4rker unterst\u00fctzt werden. Grunds\u00e4tzlich m\u00fcsse die Regierung regulatorische Rahmenbedingungen schaffen, die Innovationen, auch im sozialen und \u00f6ffentlichen Bereich, erm\u00f6glichen und die Effizienz ihrer bisherigen Bem\u00fchungen steigern. In den Bereichen Forschung und Entwicklung sei insbesondere die bessere Vermarktung der erzielten Ergebnisse von Bedeutung. Insgesamt m\u00fcsse in Australien eine Innnovationskultur entfaltet werden, die etwa durch die Einf\u00fchrung sogenannter \u201eNational Missions\u201c erreicht werden k\u00f6nne.<br \/>\n<a href=\"https:\/\/industry.gov.au\/Innovation-and-Science-Australia\/Australia-2030\/Pages\/default.aspx\" target=\"_blank\" rel=\"noopener\">https:\/\/industry.gov.au\/Innovation-and-Science-Australia\/Australia-2030\/Pages\/default.aspx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Innovation and Science Australia (ISA) ist ein unabh\u00e4ngiges Gremium, das die australische Regierung zur strategischen Ausrichtung von Wissenschaft, Forschung und Innovation ber\u00e4t. Mit dem Ende Januar vorgestellten Plan Australia 2030: Prosperity through Innovation will ISA die Regierung dabei unterst\u00fctzen, die Innovationskraft des Landes zu st\u00e4rken und bis zum Jahr 2030 die vorhandenen Potentiale voll auszusch\u00f6pfen [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134,99],"tags":[],"class_list":["post-1107","post","type-post","status-publish","format-standard","hentry","category-ausland","category-innovationen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Innovation and Science Australia ver\u00f6ffentlicht &quot;2030 Plan&quot; - KnowHow Ostwestfalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovation and Science Australia ver\u00f6ffentlicht &quot;2030 Plan&quot; - KnowHow Ostwestfalen\" \/>\n<meta property=\"og:description\" content=\"Innovation and Science Australia (ISA) ist ein unabh\u00e4ngiges Gremium, das die australische Regierung zur strategischen Ausrichtung von Wissenschaft, Forschung und Innovation ber\u00e4t. Mit dem Ende Januar vorgestellten Plan Australia 2030: Prosperity through Innovation will ISA die Regierung dabei unterst\u00fctzen, die Innovationskraft des Landes zu st\u00e4rken und bis zum Jahr 2030 die vorhandenen Potentiale voll auszusch\u00f6pfen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow Ostwestfalen\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-06T07:55:36+00:00\" \/>\n<meta name=\"author\" content=\"vvalter\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vvalter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/\"},\"author\":{\"name\":\"vvalter\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"headline\":\"Innovation and Science Australia ver\u00f6ffentlicht &#8222;2030 Plan&#8220;\",\"datePublished\":\"2018-04-06T07:55:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/\"},\"wordCount\":237,\"articleSection\":[\"Ausland\",\"Innovationen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/\",\"name\":\"Innovation and Science Australia ver\u00f6ffentlicht \\\"2030 Plan\\\" - KnowHow Ostwestfalen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\"},\"datePublished\":\"2018-04-06T07:55:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/04\\\/06\\\/innovation-and-science-australia-veroeffentlicht-2030-plan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovation and Science Australia ver\u00f6ffentlicht &#8222;2030 Plan&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\",\"name\":\"KnowHow Ostwestfalen\",\"description\":\"Innovation &amp; Technologietransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\",\"name\":\"vvalter\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innovation and Science Australia ver\u00f6ffentlicht \"2030 Plan\" - KnowHow Ostwestfalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/","og_locale":"de_DE","og_type":"article","og_title":"Innovation and Science Australia ver\u00f6ffentlicht \"2030 Plan\" - KnowHow Ostwestfalen","og_description":"Innovation and Science Australia (ISA) ist ein unabh\u00e4ngiges Gremium, das die australische Regierung zur strategischen Ausrichtung von Wissenschaft, Forschung und Innovation ber\u00e4t. Mit dem Ende Januar vorgestellten Plan Australia 2030: Prosperity through Innovation will ISA die Regierung dabei unterst\u00fctzen, die Innovationskraft des Landes zu st\u00e4rken und bis zum Jahr 2030 die vorhandenen Potentiale voll auszusch\u00f6pfen [&hellip;]","og_url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/","og_site_name":"KnowHow Ostwestfalen","article_published_time":"2018-04-06T07:55:36+00:00","author":"vvalter","twitter_misc":{"Verfasst von":"vvalter","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/#article","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/"},"author":{"name":"vvalter","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"headline":"Innovation and Science Australia ver\u00f6ffentlicht &#8222;2030 Plan&#8220;","datePublished":"2018-04-06T07:55:36+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/"},"wordCount":237,"articleSection":["Ausland","Innovationen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/","name":"Innovation and Science Australia ver\u00f6ffentlicht \"2030 Plan\" - KnowHow Ostwestfalen","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website"},"datePublished":"2018-04-06T07:55:36+00:00","author":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"breadcrumb":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/04\/06\/innovation-and-science-australia-veroeffentlicht-2030-plan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/"},{"@type":"ListItem","position":2,"name":"Innovation and Science Australia ver\u00f6ffentlicht &#8222;2030 Plan&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/","name":"KnowHow Ostwestfalen","description":"Innovation &amp; Technologietransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77","name":"vvalter"}]}},"_links":{"self":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/comments?post=1107"}],"version-history":[{"count":1,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1107\/revisions"}],"predecessor-version":[{"id":1108,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1107\/revisions\/1108"}],"wp:attachment":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/media?parent=1107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/categories?post=1107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/tags?post=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}