{"id":1072,"date":"2018-03-09T10:02:32","date_gmt":"2018-03-09T09:02:32","guid":{"rendered":"http:\/\/blog.ostwestfalen.ihk.de\/innovation\/?p=1072"},"modified":"2018-03-09T10:02:32","modified_gmt":"2018-03-09T09:02:32","slug":"jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2","status":"publish","type":"post","link":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/","title":{"rendered":"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben"},"content":{"rendered":"<p>Noch bis zum 29. M\u00e4rz k\u00f6nnen sich Hochschulabsolventinnen und -absolventen sowie Wissenschaftlerinnen und Wissenschaftler der Universit\u00e4t Paderborn, die ein Unternehmen gr\u00fcnden wollen, f\u00fcr den F\u00f6rderwettbewerb \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c des Landes Nordrhein-Westfalen bewerben. Die Gewinner werden mit bis zu 240.000 Euro aus Mitteln des Europ\u00e4ischen Fonds f\u00fcr regionale Entwicklung (EFRE) und des Landes Nordrhein-Westfalen unterst\u00fctzt.<br \/>\n\u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c richtet sich an Unternehmensprojekte in der Gr\u00fcndungsphase, die auf technologischen, betriebswirtschaftlichen oder sozialen Innovationen, aber auch auf wissensbasierten Dienstleistungen basieren. Gef\u00f6rdert werden Hochschulabsolventinnen und -absolventen und Wissenschaftlerinnen und Wissenschaftler, deren Universit\u00e4tsabschl\u00fcsse nicht l\u00e4nger als drei Jahre zur\u00fcckliegen. Der F\u00f6rderwettbewerb geht 2018 in die sechste Runde. Beim letzten Mal war die Universit\u00e4t Paderborn mit zwei Vorhaben erfolgreich. Weitere Informationen sowie die Antrags- und Bewerbungsunterlagen gibt es <a href=\"https:\/\/www.efre.nrw.de\/wege-zur-foerderung\/weitere-foerderprogramme\/start-up-hochschul-ausgruendungen-nrw\/\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noch bis zum 29. M\u00e4rz k\u00f6nnen sich Hochschulabsolventinnen und -absolventen sowie Wissenschaftlerinnen und Wissenschaftler der Universit\u00e4t Paderborn, die ein Unternehmen gr\u00fcnden wollen, f\u00fcr den F\u00f6rderwettbewerb \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c des Landes Nordrhein-Westfalen bewerben. Die Gewinner werden mit bis zu 240.000 Euro aus Mitteln des Europ\u00e4ischen Fonds f\u00fcr regionale Entwicklung (EFRE) und des Landes Nordrhein-Westfalen unterst\u00fctzt. \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c richtet sich [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,177,92],"tags":[],"class_list":["post-1072","post","type-post","status-publish","format-standard","hentry","category-foerderprogramme","category-foerderwettbewerb","category-start-ups"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben - KnowHow Ostwestfalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben - KnowHow Ostwestfalen\" \/>\n<meta property=\"og:description\" content=\"Noch bis zum 29. M\u00e4rz k\u00f6nnen sich Hochschulabsolventinnen und -absolventen sowie Wissenschaftlerinnen und Wissenschaftler der Universit\u00e4t Paderborn, die ein Unternehmen gr\u00fcnden wollen, f\u00fcr den F\u00f6rderwettbewerb \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c des Landes Nordrhein-Westfalen bewerben. Die Gewinner werden mit bis zu 240.000 Euro aus Mitteln des Europ\u00e4ischen Fonds f\u00fcr regionale Entwicklung (EFRE) und des Landes Nordrhein-Westfalen unterst\u00fctzt. \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c richtet sich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow Ostwestfalen\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-09T09:02:32+00:00\" \/>\n<meta name=\"author\" content=\"vvalter\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vvalter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/\"},\"author\":{\"name\":\"vvalter\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"headline\":\"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben\",\"datePublished\":\"2018-03-09T09:02:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/\"},\"wordCount\":142,\"articleSection\":[\"F\u00f6rderprogramme\",\"F\u00f6rderwettbewerb\",\"Start-ups\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/\",\"name\":\"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben - KnowHow Ostwestfalen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\"},\"datePublished\":\"2018-03-09T09:02:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/2018\\\/03\\\/09\\\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#website\",\"url\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/\",\"name\":\"KnowHow Ostwestfalen\",\"description\":\"Innovation &amp; Technologietransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.ostwestfalen.ihk.de\\\/innovation\\\/#\\\/schema\\\/person\\\/9b8c0574761b5b328cc98406e6cd9e77\",\"name\":\"vvalter\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben - KnowHow Ostwestfalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/","og_locale":"de_DE","og_type":"article","og_title":"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben - KnowHow Ostwestfalen","og_description":"Noch bis zum 29. M\u00e4rz k\u00f6nnen sich Hochschulabsolventinnen und -absolventen sowie Wissenschaftlerinnen und Wissenschaftler der Universit\u00e4t Paderborn, die ein Unternehmen gr\u00fcnden wollen, f\u00fcr den F\u00f6rderwettbewerb \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c des Landes Nordrhein-Westfalen bewerben. Die Gewinner werden mit bis zu 240.000 Euro aus Mitteln des Europ\u00e4ischen Fonds f\u00fcr regionale Entwicklung (EFRE) und des Landes Nordrhein-Westfalen unterst\u00fctzt. \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c richtet sich [&hellip;]","og_url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/","og_site_name":"KnowHow Ostwestfalen","article_published_time":"2018-03-09T09:02:32+00:00","author":"vvalter","twitter_misc":{"Verfasst von":"vvalter","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/#article","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/"},"author":{"name":"vvalter","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"headline":"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben","datePublished":"2018-03-09T09:02:32+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/"},"wordCount":142,"articleSection":["F\u00f6rderprogramme","F\u00f6rderwettbewerb","Start-ups"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/","name":"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben - KnowHow Ostwestfalen","isPartOf":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website"},"datePublished":"2018-03-09T09:02:32+00:00","author":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77"},"breadcrumb":{"@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/2018\/03\/09\/jetzt-fuer-programm-start-up-hochschul-ausgruendungen-bewerben-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/"},{"@type":"ListItem","position":2,"name":"Jetzt f\u00fcr Programm \u201eSTART-UP-Hochschul-Ausgr\u00fcndungen\u201c bewerben"}]},{"@type":"WebSite","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#website","url":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/","name":"KnowHow Ostwestfalen","description":"Innovation &amp; Technologietransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/#\/schema\/person\/9b8c0574761b5b328cc98406e6cd9e77","name":"vvalter"}]}},"_links":{"self":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":1,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1073,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1073"}],"wp:attachment":[{"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ostwestfalen.ihk.de\/innovation\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}